{"id":6602,"date":"2025-12-23T23:15:20","date_gmt":"2025-12-23T14:15:20","guid":{"rendered":"https:\/\/dble.bn-ent.net\/news\/?post_type=de&#038;p=6602"},"modified":"2025-12-23T23:15:52","modified_gmt":"2025-12-23T14:15:52","slug":"%e3%83%95%e3%83%ab%e3%83%91%e3%83%af%e3%83%bc%e5%ad%ab%e6%82%9f%e7%a9%ba","status":"publish","type":"de","link":"https:\/\/dble.bn-ent.net\/news\/de\/character\/6602\/","title":{"rendered":"Volle Kraft: Super-Saiyajin 4 Son-Goku F\u00e4higkeiten-Vorstellung"},"content":{"rendered":"<p><a href=\"https:\/\/ww.bandainamcoentwebstore.com\/dble-ww\/de?utm_source=dble_officialweb&#038;utm_medium=referral&#038;utm_campaign=de_character\" rel=\"noopener\" target=\"\\\\\\_blank\"><br \/>\n<img decoding=\"async\" src=\"https:\/\/wp-dble.bn-ent.net\/news\/LpOvmfE7GJ\/wp-content\/uploads\/DBL_bnr_Web-store_FAQ_1000x250_DE.png\"><\/a><\/p>\n<div>*Der hier vorgestellte Inhalt befindet sich derzeit noch in der Entwicklung und kann sich jederzeit \u00e4ndern. Bitte \u00fcberpr\u00fcft das Endresultat, nachdem es ins Spiel implementiert wurde.<\/p>\n<div><ins>ULTRA Volle Kraft: Super-Saiyajin 4 Son-Goku mit zwei superm\u00e4chtigen Features tritt dem Kampf bei!<br \/>\n<\/ins><\/p>\n<div>\n<h2>Son-Gokus St\u00e4rken:<\/h2>\n<\/div>\n<p><ins><span style=background-color:#483d8b>1)<\/small> Feature 1: Das neue Feature &#8220;Anti-Deckungswechsel-Angriff&#8221;<\/span><br \/>\nWenn der Gegner bei einem Schlag- oder Fernangriff einen Deckungswechsel ausf\u00fchrt, wird dem Gegner vor Auswechseln enormer Schaden zugef\u00fcgt und dem eingewechselten Gegner werden ebenfalls 100% des Schadens zugef\u00fcgt!<br \/>\n<br \/><span style=background-color:#483d8b>2)<\/small> Feature 2: &#8220;RR-Abwehr&#8221;<\/span><br \/>\nWenn er sich im Bereitschaftsmodus befindet, und ihr beim Kartenausw\u00e4hlen eines gegnerischen Rising Rush verliert, wird der gegnerische Rising Rush unterbrochen!<br \/>\nSchickt Son-Goku in den Bereitschaftsmodus, wenn der Gegner einen Rising Rush einsetzt!<br \/>\n<br \/><span style=background-color:#483d8b>3)<\/small> Super-offensive Einzigartige Energie<\/span><br \/>\nStartet im &#8220;Freischaltungs-Typ&#8221; mit 50% erh\u00f6htem Zugef\u00fcgten Schaden und 40% erh\u00f6hter Kritisch-Rate!<br \/>\n<br \/><span style=background-color:#483d8b>4)<\/small> Kraftvolle Kombos mit Schlag- und Fernangriffen<\/span><br \/>\nBeim 3. Einsatz einer Schlag- oder Fernangriff-K\u00fcnstekarte wird eine Spezialangriff-K\u00fcnstekarte gezogen und der Spezialangriffsschaden um 30% erh\u00f6ht!<br \/>\nVerkettet eure Kombos und beendet sie mit einem Spezialangriff!<br \/>\n<br \/>\nVolle Kraft mit vereinter St\u00e4rke! \u00dcberw\u00e4ltigt eure Gegner mit beispielloser Power!<\/ins><\/div>\n<\/div>\n<div>\n<h3>Volle Kraft: Super-Saiyajin 4 Son-Goku<\/h3>\n<p><span class=\"attribute attribute--grn\"><\/span><br \/>\n<span class=\"icon icon--tag\"><\/span>Son-Familie, Saiyajin, Super-Saiyajin 4, GT<br \/>\n<span class=\"icon icon--episode\"><\/span>Super-Baby-Saga <small>(GT)<\/small><\/div>\n<p><!-- \u2605\u2605\u2605\u2605\u2605Z\u30a2\u30d3\u30ea\u30c6\u30a3\u2605\u2605\u2605\u2605\u2605 --><\/p>\n<div>\n<h2>Z-F\u00e4higkeit<\/h2>\n<div>\n<ins>Mit der Z-F\u00e4higkeit II werden &#8220;GT&#8221; und &#8220;Son-Familie&#8221; verst\u00e4rkt!<br \/>\nAu\u00dferdem erh\u00f6ht seine Z-F\u00e4higkeit III den Spezialangriffsschaden von &#8220;GT&#8221;!<\/ins>\n<\/div>\n<div>\nZI: &#8220;<span class=\"icon icon--tag\"><\/span>GT&#8221;:<br \/>\n&#8211; Basis-Fernangriff 28%<span class=\"arrow arrow--blueup\"><\/span><br \/>\n&#8211; Basis-Fernverteidigung 28%<span class=\"arrow arrow--blueup\"><\/span><\/p>\n<p>ZII: &#8220;<span class=\"icon icon--tag\"><\/span>GT&#8221; oder &#8220;<span class=\"icon icon--tag\"><\/span>Son-Familie&#8221;:<br \/>\n&#8211; Basis-Fernangriff 30%<span class=\"arrow arrow--blueup\"><\/span><br \/>\n&#8211; Basis-Fernverteidigung 30%<span class=\"arrow arrow--blueup\"><\/span><\/p>\n<p>ZIII: &#8220;<span class=\"icon icon--tag\"><\/span>GT&#8221; oder &#8220;<span class=\"icon icon--tag\"><\/span>Son-Familie&#8221;:<br \/>\n&#8211; Basis-Fernangriff 38%<span class=\"arrow arrow--blueup\"><\/span><br \/>\n&#8211; Basis-Fernverteidigung 38%<span class=\"arrow arrow--blueup\"><\/span><\/p>\n<p>&#8220;<span class=\"icon icon--tag\"><\/span>GT&#8221;:<br \/>\n&#8211; Spezialangriffsschaden 3%<span class=\"arrow arrow--blueup\"><\/span><\/p>\n<p>ZIV: &#8220;<span class=\"icon icon--tag\"><\/span>GT&#8221; oder &#8220;<span class=\"icon icon--tag\"><\/span>Son-Familie&#8221;:<br \/>\n&#8211; Basis-Fernangriff 42%<span class=\"arrow arrow--blueup\"><\/span><br \/>\n&#8211; Basis-Fernverteidigung 42%<span class=\"arrow arrow--blueup\"><\/span><\/p>\n<p>&#8220;<span class=\"icon icon--tag\"><\/span>GT&#8221;:<br \/>\n&#8211; Spezialangriffsschaden 5%<span class=\"arrow arrow--blueup\"><\/span>\n<\/div>\n<\/div>\n<p><!-- \u2605\u2605\u2605\u2605\u2605ULTRA\u30a2\u30d3\u30ea\u30c6\u30a3\u2605\u2605\u2605\u2605\u2605 --><\/p>\n<div>\n<h2>ULTRA-F\u00e4higkeit<\/h2>\n<div>\n<ins>Wenn er als Anf\u00fchrer gew\u00e4hlt wird, erh\u00e4lt er ein massives Power-Up!<\/ins>\n<\/div>\n<div>\n\u25bcWenn Anf\u00fchrer:<br \/>\n&#8211; Zugef\u00fcgter Schaden 30%<span class=\"arrow arrow--blueup\"><\/span><small>(nicht eliminierbar)<\/small><br \/>\n&#8211; Ki-Regenerationsgeschwindigkeit 30%<span class=\"arrow arrow--blueup\"><\/span><small>(nicht eliminierbar)<\/small><\/p>\n<p>\u25bcWenn nicht Anf\u00fchrer, pro &#8220;<span class=\"icon icon--tag\"><\/span>GT&#8221;-Kampf-\/Hilfsmitglied:<br \/>\n&#8211; Zugef\u00fcgter Schaden je 5%<span class=\"arrow arrow--blueup\"><\/span><small>(nicht eliminierbar)<\/small><br \/>\n&#8211; Ki-Regenerationsgeschwindigkeit je 5%<span class=\"arrow arrow--blueup\"><\/span><small>(nicht eliminierbar)<\/small><\/p>\n<p>*Es werden maximal 3 Hilfsmitglieder gez\u00e4hlt\n<\/p><\/div>\n<\/div>\n<p><!-- \u2605\u2605\u2605\u2605\u2605\u6253\u6483\u30a2\u30fc\u30c4\u2605\u2605\u2605\u2605\u2605 --><\/p>\n<div>\n<h2><span class=\"head-img\"><img decoding=\"async\" src=\"https:\/\/wp-dble.bn-ent.net\/news\/LpOvmfE7GJ\/wp-content\/uploads\/2023\/03\/HUD_CardStrike.png\"><\/span>Schlagangriff<\/h2>\n<div>\n<ins>Verf\u00fcgt \u00fcber eine Panzerung, die es erm\u00f6glicht, loszust\u00fcrmen, ohne sich um gegnerische Fernangriffe sorgen zu m\u00fcssen!<br \/>\nRegeneriert bei Einsatz Lebensenergie!<\/ins>\n<\/div>\n<div>\nSchlagangriff <small>(Schock)<\/small><br \/>\nRegeneriert 4% Lebensenergie\n<\/div>\n<div class=\"text-wrap__img text-wrap__img--half\">\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wp-dble.bn-ent.net\/news\/LpOvmfE7GJ\/wp-content\/uploads\/\u5c04\u6483\u30a2\u30fc\u30de\u30fc.png\" alt=\"\" width=\"84\" height=\"132\" class=\"aligncenter size-full wp-image-5655\" \/>\n<\/div>\n<\/div>\n<p><!-- \u2605\u2605\u2605\u2605\u2605\u5c04\u6483\u30a2\u30fc\u30c4\u2605\u2605\u2605\u2605\u2605 --><\/p>\n<div>\n<h2><span class=\"head-img\"><img decoding=\"async\" src=\"https:\/\/wp-dble.bn-ent.net\/news\/LpOvmfE7GJ\/wp-content\/uploads\/2023\/03\/HUD_CardShot.png\"><\/span>Fernangriff<\/h2>\n<div>\n<ins>Erh\u00f6ht bei Einsatz den Zugef\u00fcgten Schaden!<\/ins>\n<\/div>\n<div>\nFernangriff <small>(Schock)<\/small><br \/>\nZugef\u00fcgter Schaden 15%<span class=\"arrow arrow--blueup\"><\/span><small>(10 Zeiteinheiten)<\/small>\n<\/div>\n<\/div>\n<p><!-- \u2605\u2605\u2605\u2605\u2605\u5fc5\u6bba\u30a2\u30fc\u30c4\u2605\u2605\u2605\u2605\u2605 --><\/p>\n<div>\n<h2><span class=\"head-img\"><img decoding=\"async\" src=\"https:\/\/wp-dble.bn-ent.net\/news\/LpOvmfE7GJ\/wp-content\/uploads\/2023\/03\/HUD_CardSpecial.png\"><\/span>Spezialangriff<\/h2>\n<div>\n<ins>Bei einem Treffer wird die Verschwinden-Leiste erheblich regeneriert, was die Kampff\u00fchrung erleichtert!<\/ins>\n<\/div>\n<div>\nExtremer Schaden <small>(Schock)<\/small><\/p>\n<p>\u25bcEffekte:<br \/>\n&#8211; Spezialangriffsschaden 50%<span class=\"arrow arrow--blueup\"><\/span><small>(3 Zeiteinheiten)<\/small><\/p>\n<p>\u25bcBei Treffer:<br \/>\n&#8211; Regeneriert 70% Verschwinden-Leiste<br \/>\n&#8211; Verb\u00fcndete: Wartezeit 2<span class=\"arrow arrow--bluedown\"><\/span><\/p>\n<\/div>\n<div class=\"text-wrap__img text-wrap__img--half\">\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wp-dble.bn-ent.net\/news\/LpOvmfE7GJ\/wp-content\/uploads\/\u5c04\u6483\u30a2\u30fc\u30de\u30fc.png\" alt=\"\" width=\"84\" height=\"132\" class=\"aligncenter size-full wp-image-5655\" \/>\n<\/div>\n<\/div>\n<p><!-- \u2605\u2605\u2605\u2605\u2605\u7279\u6b8a\u30a2\u30fc\u30c4\u2605\u2605\u2605\u2605\u2605 --><\/p>\n<div>\n<h2><span class=\"head-img\"><img decoding=\"async\" src=\"https:\/\/wp-dble.bn-ent.net\/news\/LpOvmfE7GJ\/wp-content\/uploads\/2023\/03\/HUD_CardExtra.png\"><\/span>Superangriff<\/h2>\n<div>\n<ins>Ein weitreichender Superangriff, der es erleichtert, Kombos zu rauben!<br \/>\nBei Treffer wird Handschutz gew\u00e4hrt und Super-Deckungswechsel eliminiert, was das Fortsetzen der Kombo erleichtert!<\/ins>\n<\/div>\n<div>\n\u25bcEffekte:<br \/>\n&#8211; Regeneriert 10% Lebensenergie<br \/>\n&#8211; Regeneriert 50 Ki<\/p>\n<p>\u25bcBei Treffer:<br \/>\n&#8211; Bei 3 oder weniger Karten: zieht 1 Karte<br \/>\n&#8211; Einzigartige Energie 20%<span class=\"arrow arrow--blueup\"><\/span><br \/>\n&#8211; Eliminiert Super-Deckungswechsel <small>(5 Zeiteinheiten)<\/small><br \/>\n&#8211; Handschutz <small>(5 Zeiteinheiten)<\/small><\/p>\n<p>[M\u00f6gliche Folgeangriffe]<br \/>\n<span class=\"arts arts--strike\"><\/span><span class=\"arts arts--blast\"><\/span><span class=\"arts arts--specialmove\"><\/span><span class=\"arts arts--ultimate\"><\/span>\n<\/div>\n<\/div>\n<p><!-- \u2605\u2605\u2605\u2605\u2605\u7a76\u6975\u30a2\u30fc\u30c4\u2605\u2605\u2605\u2605\u2605 --><\/p>\n<div>\n<h2><span class=\"head-img\"><img decoding=\"async\" src=\"https:\/\/wp-dble.bn-ent.net\/news\/LpOvmfE7GJ\/wp-content\/uploads\/2023\/03\/HUD_CardUltimate.png\"><\/span>Finaler Angriff<\/h2>\n<div>\n<ins>Bei Einsatz wird der kritische Schaden erh\u00f6ht!<br \/>\nAu\u00dferdem wird bei Treffer das Ki des Gegners um 100 gesenkt!<\/ins>\n<\/div>\n<div>\nGigantischer Schaden <small>(Schock)<\/small><\/p>\n<p>\u25bcEffekte:<br \/>\n&#8211; Finaler-Angriffsschaden 30%<span class=\"arrow arrow--blueup\"><\/span><small>(3 Zeiteinheiten)<\/small><br \/>\n&#8211; Kritischer Schaden 30%<span class=\"arrow arrow--blueup\"><\/span><small>(3 Zeiteinheiten)<\/small><br \/>\n&#8211; Eliminiert Standhaftigkeit <small>(3 Zeiteinheiten)<\/small><\/p>\n<p>\u25bcBei Treffer:<br \/>\n&#8211; Gegner: Ki 100<span class=\"arrow arrow--reddown\"><\/span><\/p>\n<\/div>\n<div class=\"text-wrap__img text-wrap__img--half\">\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wp-dble.bn-ent.net\/news\/LpOvmfE7GJ\/wp-content\/uploads\/\u5c04\u6483\u30a2\u30fc\u30de\u30fc.png\" alt=\"\" width=\"84\" height=\"132\" class=\"aligncenter size-full wp-image-5655\" \/>\n<\/div>\n<\/div>\n<p><!-- \u2605\u2605\u2605\u2605\u2605\u30e1\u30a4\u30f3\u30a2\u30d3\u30ea\u30c6\u30a3\u2605\u2605\u2605\u2605\u2605 --><\/p>\n<div>\n<h2>Hauptf\u00e4higkeit<\/h2>\n<div>\n<ins>F\u00fcllt 100% der Einzigartigen Energie!<br \/>\nWechselt zum &#8220;Freischaltungs-Typ&#8221;, um eure Feuerkraft massiv zu erh\u00f6hen und versucht euch dann an einem Finalen Angriff!<\/ins>\n<\/div>\n<div>\n&#8211; Zerst\u00f6rt 1 Karte und zieht als N\u00e4chstes Finaler-Angriff-K\u00fcnstekarte<br \/>\n&#8211; Regeneriert 30% Lebensenergie<br \/>\n&#8211; Regeneriert 50 Ki<br \/>\n&#8211; Einzigartige Energie 100%<span class=\"arrow arrow--blueup\"><\/span><br \/>\n&#8211; Eliminiert Attributsabz\u00fcge und Statuseffekte<br \/>\n&#8211; Eliminiert Kartensatz-Versiegelung<\/p>\n<p>*Bedingung:<br \/>\nnach 25 Zeiteinheiten\n<\/p><\/div>\n<\/div>\n<p><!-- \u2605\u2605\u2605\u2605\u2605\u30b9\u30bf\u30fc\u30bf\u30fc\u30a2\u30d3\u30ea\u30c6\u30a3\u2605\u2605\u2605\u2605\u2605 --><\/p>\n<div>\n<h2>Start-F\u00e4higkeiten<\/h2>\n<div>\n<ins>Wenn 1 oder mehr verb\u00fcndete &#8220;GT&#8221; im Team sind, werden der Zugef\u00fcgte Schaden und die Schadensabwehr weiter verst\u00e4rkt und er erh\u00e4lt Standhaftigkeit!<\/ins>\n<\/div>\n<div>\n&#8211; Zugef\u00fcgter Schaden 310%<span class=\"arrow arrow--blueup\"><\/span><br \/>\n&#8211; Schadensabwehr 240%<span class=\"arrow arrow--blueup\"><\/span><br \/>\n&#8211; Ki-Regenerationsgeschwindigkeit 100%<span class=\"arrow arrow--blueup\"><\/span><br \/>\n&#8211; K\u00fcnstekarten-Ziehgeschwindigkeit 1<span class=\"arrow arrow--blueup\"><\/span><\/p>\n<p>Au\u00dferdem, wenn mind. 1 verb\u00fcndeter &#8220;<span class=\"icon icon--tag\"><\/span>GT&#8221; <small>(au\u00dfer selbst)<\/small> Kampfmitglied ist:<br \/>\n&#8211; Zugef\u00fcgter Schaden 20%<span class=\"arrow arrow--blueup\"><\/span><br \/>\n&#8211; Schadensabwehr 20%<span class=\"arrow arrow--blueup\"><\/span><br \/>\n&#8211; Standhaftigkeit <small>(regeneriert 50%)<\/small><\/p>\n<p>*Alle Effekte nicht eliminierbar\n<\/p><\/div>\n<\/div>\n<p><!-- \u2605\u2605\u2605\u2605\u2605\u30e6\u30cb\u30fc\u30af\u30a2\u30d3\u30ea\u30c6\u30a3\u2605\u2605\u2605\u2605\u2605 --><\/p>\n<div>\n<h2>Einzigartige F\u00e4higkeit<\/h2>\n<div>\n<ins>Neben den superm\u00e4chtigen neuen Features &#8220;Anti-Deckungswechsel-Angriff&#8221; und &#8220;RR-Abwehr&#8221; besitzt er noch weitere starke F\u00e4higkeiten!<br \/>\n<br \/>\n\u25bcAngriff<br \/>\nNach Einsatz von 3 Schlag- oder Fernangriff-K\u00fcnstekarten, wird 1 Spezialangriff-K\u00fcnstekarte gezogen und der Spezialangriffsschaden um 30% erh\u00f6ht!<br \/>\n<br \/>\n\u25bcVerteidigung<br \/>\nNach Erleiden von 3 gegnerischen Schlag- oder Fernangriffen, werden gegnerische Schlag-, Fern- und Superangriff-K\u00fcnstekarten versiegelt!<\/ins>\n<\/div>\n<div>\n\u25bcBei Kampfantritt:<br \/>\n&#8211; Bei 3 oder weniger Karten: zieht 1 Karte<br \/>\n&#8211; Regeneriert 15% Lebensenergie<br \/>\n&#8211; Regeneriert 40 Ki<br \/>\n&#8211; Eliminiert Super-Deckungswechsel <small>(5 Zeiteinheiten)<\/small><br \/>\n&#8211; Eliminiert Elementschw\u00e4che bei Erlittenem Schaden <small>(5 Zeiteinheiten)<\/small><\/p>\n<p>\u25bcJe nach Anzahl der Schlag-\/Fernangriffe:<br \/>\n*Einsatz einer Spezialangriff-K\u00fcnstekarte oder Auswechslung setzt den Z\u00e4hler zur\u00fcck<br \/>\n[Ab dem 1. Mal]<br \/>\n&#8211; Durchst\u00f6\u00dft Schadensabwehr zu 20% <small>(10 Zeiteinheiten)<\/small><br \/>\n[3. Mal]<br \/>\n&#8211; Zieht als N\u00e4chstes Spezialangriff-K\u00fcnstekarte<br \/>\n&#8211; Regeneriert 50 Ki<br \/>\n&#8211; Spezialangriffsschaden 30%<span class=\"arrow arrow--blueup\"><\/span><small>(5 Zeiteinheiten)<\/small><\/p>\n<p>\u25bcIm Kampf, je nach Anzahl der erlittenen Schlag-\/Fernangriffe durch den Gegner:<br \/>\n*Auswechslung setzt die Anzahl der erlittenen K\u00fcnsteangriffe zur\u00fcck<br \/>\n[Ab dem 1. Mal]<br \/>\n&#8211; Alle Gegner: Kosten f\u00fcr Schlag-\/Fernangriffe 5<span class=\"arrow arrow--redup\"><\/span><small>(10 Zeiteinheiten)<\/small><br \/>\n[3. Mal]<br \/>\n&#8211; Gegner: versiegelt Schlag-\/Fern-\/Superangriff-K\u00fcnstekarten <small>(3 Zeiteinheiten)<\/small><\/p>\n<p>\u25bcIm Kampf, bei Einsatz eines Spezial-, Finalen-, Erweckungsangriffs oder Rising Rush durch den Gegner:<br \/>\n&#8211; Regeneriert 15% Lebensenergie <small>(3 Mal)<\/small><\/p>\n<p>Au\u00dferdem, wenn mind. 1 verb\u00fcndeter &#8220;<span class=\"icon icon--tag\"><\/span>GT&#8221; <small>(au\u00dfer selbst)<\/small> Kampfmitglied ist:<br \/>\n&#8211; Verb\u00fcndete: Wartezeit 5<span class=\"arrow arrow--bluedown\"><\/span><br \/>\n&#8211; Gegner: eliminiert Statusverst\u00e4rkungen <small>(3 Mal)<\/small><\/p>\n<p>\u25bcIm Bereitschaftsmodus, bei Niederlage beim Kartenausw\u00e4hlen w\u00e4hrend eines Rising Rush des Gegners <small>(1 Mal)<\/small>:<br \/>\n&#8211; Aktiviert RR-Abwehr und betritt den Kampf<\/p>\n<p>\u25bcBeim gegnerischen Deckungswechsel w\u00e4hrend eines Schlag- oder Fernangriffs <small>(1 Mal)<\/small>:<br \/>\n&#8211; Aktiviert Anti-Deckungswechsel-Angriff<br \/>\n&#8211; Gegner vor Auswechslung: enormer Schaden <small>(Schock)<\/small><br \/>\nAu\u00dferdem, Gegner nach Auswechslung erh\u00e4lt 100% des Schadens<br \/>\n&#8211; Eliminiert Elementschw\u00e4che <small>(3 Zeiteinheiten)<\/small><\/p>\n<p>[M\u00f6gliche Folgeangriffe]<br \/>\n<span class=\"arts arts--strike\"><\/span><span class=\"arts arts--blast\"><\/span><span class=\"arts arts--specialmove\"><\/span><span class=\"arts arts--ultimate\"><\/span>\n<\/div>\n<\/div>\n<p><!-- \u2605\u2605\u2605\u2605\u2605\u7279\u6b8a\u30ab\u30d0\u30fc\u30c1\u30a7\u30f3\u30b8\u2605\u2605\u2605\u2605\u2605 --><\/p>\n<div>\n<h2>Super-Deckungswechsel<\/h2>\n<div>\n<ins>Besitzt einen Super-Deckungswechsel gegen Schlagangriffe!<\/ins>\n<\/div>\n<div>\n[Betreffende K\u00fcnste]<br \/>\n<span class=\"arts arts--strike\"><\/span><\/p>\n<p>[M\u00f6gliche Folgeangriffe]<br \/>\n<span class=\"arts arts--specialmove\"><\/span>\n<\/div>\n<\/div>\n<p><!-- \u2605\u2605\u2605\u2605\u2605\u30e6\u30cb\u30fc\u30af\u30b2\u30fc\u30b8\u2605\u2605\u2605\u2605\u2605 --><\/p>\n<div>\n<h2>Einzigartige Energie<\/h2>\n<div>\n<ins>Startet im &#8220;Freischaltungs-Typ&#8221;!<br \/>\nIm Freischaltungs-Typ wird der Zugef\u00fcgte Schaden um 50% und Kritisch-Rate um 40% erh\u00f6ht und Statuseffekte eliminiert!<br \/>\n<br \/>\nWechselt zum &#8220;Erlittener-Schaden-Typ&#8221;, wenn die Einzigartige Energie auf 0% sinkt, und bei Erleiden eines gegnerischen Angriffs f\u00fcllt sich die Einzigartige Energie stark!<br \/>\nSobald sie max. aufgeladen ist, wechselt sie erneut in den Freischaltungs-Typ!<\/ins>\n<\/div>\n<div>\n&#8220;Freischaltungs-Typ&#8221; \u21d4 &#8220;Erlittener-Schaden-Typ&#8221;<br \/>\n<span class=\"uniga uniga--unleash\"><\/span><ICN=ArrowMark><span class=\"uniga uniga--def\"><\/span><br \/>\n*Beginnt als &#8220;Freischaltungs-Typ&#8221;<br \/>\n*Beginnt mit 100% Einzigartiger Energie<\/p>\n<p>\u25bcWenn &#8220;Freischaltungs-Typ&#8221;:<br \/>\n&#8211; Zugef\u00fcgter Schaden 50%<span class=\"arrow arrow--blueup\"><\/span><small>(nicht eliminierbar)<\/small><br \/>\n&#8211; Schadensabwehr 20%<span class=\"arrow arrow--blueup\"><\/span><small>(nicht eliminierbar)<\/small><br \/>\n&#8211; Kritisch-Rate 40%<span class=\"arrow arrow--blueup\"><\/span><small>(nicht eliminierbar)<\/small><br \/>\n&#8211; Eliminiert Statuseffekte<\/p>\n<p>\u25bcWenn Einzigartige Energie bei 0% [Freischaltungs-Typ]:<br \/>\n&#8211; Wechselt zu &#8220;Erlittener-Schaden-Typ&#8221;<\/p>\n<p>\u25bcWenn max. gef\u00fcllt [Erlittener-Schaden-Typ]:<br \/>\n&#8211; Wechselt zu &#8220;Freischaltungs-Typ&#8221;<br \/>\n&#8211; Zieht als N\u00e4chstes Superangriff-K\u00fcnstekarte<br \/>\n&#8211; Regeneriert 20% Lebensenergie<br \/>\n&#8211; Eliminiert Attributsabz\u00fcge<\/p>\n<p>*F\u00fcll-Bedingung [Erlittener-Schaden-Typ]:<br \/>\nBei jedem erlittenen K\u00fcnsteangriff des Gegners: f\u00fcllt sich stark<\/p>\n<p>*Bedingung f\u00fcr Verbrauch [Freischaltungs-Typ]:<br \/>\nIm Kampf: wird verbraucht\n<\/p><\/div>\n<\/div>\n","protected":false},"template":"","de_category":[9],"class_list":["post-6602","de","type-de","status-publish","hentry","de_category-character"],"acf":{"img":false,"movie_url":"https:\/\/www.youtube.com\/watch?v=rxxCiPiiwuw","movie_mp4":false,"movie_mp4_img":false},"terms":{"\u30ab\u30c6\u30b4\u30ea\u30fc":[{"term_id":9,"name":"Charaktere","slug":"character","term_group":0,"term_taxonomy_id":9,"taxonomy":"de_category","description":"\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u306e\u30ab\u30c6\u30b4\u30ea\u30fc","parent":0,"count":78,"filter":"raw","term_order":"0"}]},"_links":{"self":[{"href":"https:\/\/dble.bn-ent.net\/news\/wp-json\/wp\/v2\/de\/6602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dble.bn-ent.net\/news\/wp-json\/wp\/v2\/de"}],"about":[{"href":"https:\/\/dble.bn-ent.net\/news\/wp-json\/wp\/v2\/types\/de"}],"version-history":[{"count":5,"href":"https:\/\/dble.bn-ent.net\/news\/wp-json\/wp\/v2\/de\/6602\/revisions"}],"predecessor-version":[{"id":6642,"href":"https:\/\/dble.bn-ent.net\/news\/wp-json\/wp\/v2\/de\/6602\/revisions\/6642"}],"wp:attachment":[{"href":"https:\/\/dble.bn-ent.net\/news\/wp-json\/wp\/v2\/media?parent=6602"}],"wp:term":[{"taxonomy":"de_category","embeddable":true,"href":"https:\/\/dble.bn-ent.net\/news\/wp-json\/wp\/v2\/de_category?post=6602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}